{"id":8764,"date":"2018-02-13T13:30:55","date_gmt":"2018-02-13T12:30:55","guid":{"rendered":"http:\/\/messtec-masters.de\/?p=8764"},"modified":"2018-02-14T10:52:03","modified_gmt":"2018-02-14T09:52:03","slug":"ltt24-das-high-performance-messgeraet","status":"publish","type":"post","link":"https:\/\/messweb-masters.de\/en\/ltt24-das-high-performance-messgeraet\/","title":{"rendered":"LTT24: Das High-Performance-Messger\u00e4t"},"content":{"rendered":"<p><strong><a href=\"https:\/\/messtec-masters.de\/aussteller\/profile\/ltt-labortechnik-tasler\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"logo alignright\" src=\"https:\/\/messtec-masters.de\/wp-content\/uploads\/logo\/2018-LTT.svg\" \/><\/a>LTT24 \u2013 analoge Eing\u00e4nge, Sensorversorgungen, galvanische Trennung, 24 Bit AD-Wandlung mit bis zu 4 MHz pro Kanal,\u00a0interne SSD und 20 Bit DACs zur originalgetreuen analogen Ausgabe. \u00dcber USB 3.0 oder Ethernet werden die Daten in Echtzeit zum PC \u00fcbertragen und dort visualisiert, verrechnet und in ausw\u00e4hlbaren Datenformaten abgespeichert.<\/strong><\/p>\n<p>Die integrierten Vorverst\u00e4rker erlauben den individuellen Anschluss unterschiedlichster Sensoren, wie z. B. Volt, Strom, DMS, ICP, Ladung, PT100 etc. welche f\u00fcr jeden Kanal individuell mit nur einem Mausklick umgeschaltet werden k\u00f6nnen. So sind auch unerwartete Messaufgaben f\u00fcr die Zukunft kein Problem. Das sehr robuste und kompakte Geh\u00e4use des LTT24 erm\u00f6glicht selbst mobile und raue Eins\u00e4tze. Zur Budgetoptimierung k\u00f6nnen alle Optionen des LTT24 ganz nach Ihrem Bedarf bei Bestellung ausgew\u00e4hlt und kombiniert werden. Eine hochqualifizierte technische Beratung sowie die\u00a0Verf\u00fcgbarkeit von Vorf\u00fchrger\u00e4ten bieten den optimalen Einstieg in jedes Projekt!<\/p>\n<p><a href=\"http:\/\/www.tasler.de\/\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8767\" data-permalink=\"https:\/\/messweb-masters.de\/en\/ltt24-das-high-performance-messgeraet\/ltt24_bmw_2_25\/\" data-orig-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2018\/02\/LTT24_BMW_2_25-e1518092351761.jpg?fit=300%2C169&amp;ssl=1\" data-orig-size=\"300,169\" data-comments-opened=\"0\" data-image-title=\"LTT24_BMW_2_25\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2018\/02\/LTT24_BMW_2_25-e1518092351761.jpg?fit=300%2C169&amp;ssl=1\" class=\"alignleft wp-image-8767 size-medium\" title=\"\" src=\"https:\/\/i0.wp.com\/messtec-masters.de\/wp-content\/uploads\/2018\/02\/LTT24_BMW_2_25-300x169.jpg?resize=300%2C169&#038;ssl=1\" alt=\"\" width=\"300\" height=\"169\" data-large-file=\"https:\/\/messtec-masters.de\/wp-content\/uploads\/2018\/02\/LTT24_BMW_2_25-e1518092351761.jpg\" data-medium-file=\"https:\/\/messtec-masters.de\/wp-content\/uploads\/2018\/02\/LTT24_BMW_2_25-300x169.jpg\" data-image-description=\"\" data-image-title=\"LTT24_BMW_2_25\" data-image-meta=\"{\" data-comments-opened=\"0\" data-orig-size=\"300,169\" data-orig-file=\"https:\/\/messtec-masters.de\/wp-content\/uploads\/2018\/02\/LTT24_BMW_2_25-e1518092351761.jpg\" data-permalink=\"https:\/\/messtec-masters.de\/?attachment_id=8767\" data-attachment-id=\"8767\" \/><\/a><\/p>\n<p>Wir freuen uns auf Ihren Besuch beim messtec + sensor masters 2018<br \/>\nin Stuttgart \u2013 <strong>Stand-Nr. 1 B<\/strong>!<\/p>\n<p><a href=\"http:\/\/www.tasler.de\/\" target=\"_blank\" rel=\"noopener\">www.tasler.de<\/a> \u2013 <strong>wen<\/strong><strong>n es um pr\u00e4zise, schnelle und\u00a0<\/strong><strong>flexible Messtechnik geht<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LTT24 \u2013 analoge Eing\u00e4nge, Sensorversorgungen, galvanische Trennung, 24 Bit AD-Wandlung mit bis zu 4 MHz pro Kanal,\u00a0interne SSD und 20 Bit DACs zur originalgetreuen analogen Ausgabe. \u00dcber USB 3.0 oder Ethernet werden die Daten in Echtzeit zum PC \u00fcbertragen und&#8230;<\/p>\n","protected":false},"author":6,"featured_media":8767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[102,21,99],"class_list":["post-8764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte","tag-messgeraet","tag-verstarker","tag-wandler"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2018\/02\/LTT24_BMW_2_25-e1518092351761.jpg?fit=300%2C169&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8ayXV-2hm","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/8764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/comments?post=8764"}],"version-history":[{"count":18,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/8764\/revisions"}],"predecessor-version":[{"id":8885,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/8764\/revisions\/8885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media\/8767"}],"wp:attachment":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media?parent=8764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/categories?post=8764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/tags?post=8764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}