{"id":5874,"date":"2016-03-04T12:01:43","date_gmt":"2016-03-04T11:01:43","guid":{"rendered":"http:\/\/www.dh-premiumevents.de\/extern\/wordpress-Produkte\/?p=5770"},"modified":"2016-09-26T12:30:55","modified_gmt":"2016-09-26T10:30:55","slug":"ipetronik-ipecloud-intelligente-und-effiziente-flottenerprobung","status":"publish","type":"post","link":"https:\/\/messweb-masters.de\/en\/ipetronik-ipecloud-intelligente-und-effiziente-flottenerprobung\/","title":{"rendered":"IPETRONIK: IPEcloud \u2013 Intelligente und effiziente Flottenerprobung"},"content":{"rendered":"<p><a href=\"http:\/\/www.ipetronik.com\" target=\"_blank\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/i0.wp.com\/www.dh-premiumevents.de\/extern\/wordpress\/wp-content\/uploads\/XContainer\/Firmenlogos\/Ipetronik.png?resize=116%2C58\" alt=\"\" width=\"116\" height=\"58\" \/><\/a><strong>Steigende Anforderungen in automobilen Entwicklungsprozessen verlangen effiziente Qualit\u00e4tsmanagement-Systeme in den Bereichen Fahrerprobung und Flottentest. Die IPEcloud bietet in Verbindung mit den IPETRONIK-Datenloggern vielf\u00e4ltige Funktionen zur Umsetzung eines optimalen Flottenprojekts.<\/strong><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/dh-premiumevents.de\/extern\/MesstecMasters\/2015\/wp-content\/uploads\/2016\/03\/IPEcloud.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5894\" data-permalink=\"https:\/\/messweb-masters.de\/en\/ipetronik-ipecloud-intelligente-und-effiziente-flottenerprobung\/ipecloud\/\" data-orig-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2016\/03\/IPEcloud.jpg?fit=922%2C922&amp;ssl=1\" data-orig-size=\"922,922\" data-comments-opened=\"0\" data-image-title=\"ipecloud\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2016\/03\/IPEcloud.jpg?fit=922%2C922&amp;ssl=1\" class=\"alignleft size-medium wp-image-5894\" src=\"https:\/\/i0.wp.com\/dh-premiumevents.de\/extern\/MesstecMasters\/2015\/wp-content\/uploads\/2016\/03\/IPEcloud-300x300.jpg?resize=300%2C300\" alt=\"ipecloud\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2016\/03\/IPEcloud.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2016\/03\/IPEcloud.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2016\/03\/IPEcloud.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2016\/03\/IPEcloud.jpg?w=922&amp;ssl=1 922w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Neben Grenzwert-Definition und zuverl\u00e4ssiger Messdaten-Erfassung einzelner Fahrzeuge oder ganzer Flotten sowie unmittelbarer Daten-Zustellung sind w\u00e4hrend der Erprobungsphase auch individuelle Vorauswertungen und Statusinformationen abrufbar.<\/p>\n<p>Die drei IPEcloud-Hauptkomponenten bestehen aus:<\/p>\n<ul>\n<li>IPEfleet \u2013 Flottenmanagement zum Monitoring der Fahrzeuge<\/li>\n<li>IPEdrive \u2013 Speicherung und Verwaltung der vom Logger erfassten Messdateien<\/li>\n<li>IPEmail \u2013 Mailserver zum Versenden von Status- und Alarmbenachrichtigungen<\/li>\n<\/ul>\n<p>Das IPEcloud-Paket beinhaltet au\u00dferdem die Bereitstellung der entsprechenden Serverkapazit\u00e4t sowie eine sichere Daten\u00fcbertragung durch verschl\u00fcsselte \u00dcbertragungsprotokolle wie HTTPS und SFTP.<\/p>\n<p>Weitere technische Details zur IPEcloud finden Sie auf der IPETRONIK-Website: <strong><a href=\"http:\/\/www.ipetronik.com\" target=\"_blank\">www.ipetronik.com<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Steigende Anforderungen in automobilen Entwicklungsprozessen verlangen effiziente Qualit\u00e4tsmanagement-Systeme in den Bereichen Fahrerprobung und Flottentest. Die IPEcloud bietet in Verbindung mit den IPETRONIK-Datenloggern vielf\u00e4ltige Funktionen zur Umsetzung eines optimalen Flottenprojekts. Neben Grenzwert-Definition und zuverl\u00e4ssiger Messdaten-Erfassung einzelner Fahrzeuge oder ganzer Flotten sowie&#8230;<\/p>\n","protected":false},"author":4,"featured_media":5894,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[71,51,28],"class_list":["post-5874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte","tag-cloud","tag-datenlogger","tag-software"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2016\/03\/IPEcloud.jpg?fit=922%2C922&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8ayXV-1wK","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/5874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/comments?post=5874"}],"version-history":[{"count":1,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/5874\/revisions"}],"predecessor-version":[{"id":5895,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/5874\/revisions\/5895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media\/5894"}],"wp:attachment":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media?parent=5874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/categories?post=5874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/tags?post=5874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}