{"id":52516,"date":"2025-12-17T10:50:18","date_gmt":"2025-12-17T09:50:18","guid":{"rendered":"https:\/\/messweb-masters.de\/?p=52516"},"modified":"2025-12-17T10:50:18","modified_gmt":"2025-12-17T09:50:18","slug":"datatec-buendelt-weiterbildungsangebote-in-neuem-eventkalender","status":"publish","type":"post","link":"https:\/\/messweb-masters.de\/en\/datatec-buendelt-weiterbildungsangebote-in-neuem-eventkalender\/","title":{"rendered":"dataTec b\u00fcndelt Weiterbildungsangebote in neuem Eventkalender"},"content":{"rendered":"<p><strong><a href=\"https:\/\/messweb-masters.de\/aussteller\/profile\/datatec\/\"><img decoding=\"async\" class=\"logo alignright\" src=\"https:\/\/messweb-masters.de\/wp-content\/uploads\/2024\/03\/2024_dataTec_mClaim.svg\" \/><\/a>Schulungen, Webinare, Herstellerworkshops \u2013 diese und weitere hochwertige Weiterbildungsangebote f\u00fchrt der neue digitale Eventkalender des Messtechnik-Distributors dataTec jetzt erstmals an einem Ort zusammen. Die kompakte Online-\u00dcbersicht l\u00e4sst sich nach Datum, Themenfeld und Format filtern und bietet die M\u00f6glichkeit, Termine direkt in g\u00e4ngige Kalenderprogramme zu \u00fcbernehmen oder intern zu teilen.<\/strong><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"52520\" data-permalink=\"https:\/\/messweb-masters.de\/en\/datatec-eventkalender-300x300\/\" data-orig-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/12\/dataTec-Eventkalender-300x300-1.jpg?fit=300%2C300&amp;ssl=1\" data-orig-size=\"300,300\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1764775238&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dataTec-Eventkalender-300&amp;#215;300\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/12\/dataTec-Eventkalender-300x300-1.jpg?fit=300%2C300&amp;ssl=1\" class=\"alignleft wp-image-52520\" src=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/12\/dataTec-Eventkalender-300x300-1.jpg?resize=300%2C300&#038;ssl=1\" alt=\"\" width=\"300\" height=\"300\" title=\"\" srcset=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/12\/dataTec-Eventkalender-300x300-1.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/12\/dataTec-Eventkalender-300x300-1.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Der Start des neuen Eventkalenders ist mit einem Ausbau des Programms verbunden; bereits im Februar und M\u00e4rz gibt es zus\u00e4tzliche Termine. Auf dem Plan stehen Schulungen zu den Normen VDE 0701 und VDE 0702, eine vertiefende Praxiseinheit zu diesen Pr\u00fcfstandards sowie verschiedene Kurse zu LabVIEW Core 1 und Core 2. Erg\u00e4nzt wird das Angebot durch ein Seminar zur Testprogramm-Entwicklung mit TestStand und eine Anwenderschulung zur Gossen-Metrawatt-Software IZYTRONIQ f\u00fcr die Profitest-Serie.<\/p>\n<p>Der neue dataTec Eventkalender wird fortlaufend um neue Formate erweitert und soll Fachkr\u00e4fte aus Entwicklung, Service und Qualit\u00e4tssicherung bei ihrer Planung unterst\u00fctzen. Das Tool ist mit einem Klick erreichbar unter:<br \/>\n<a href=\"https:\/\/www.datatec.eu\/eventkalender\" target=\"_blank\" rel=\"noopener\">www.datatec.eu\/eventkalender.<\/a><span class='maxbutton-103-container mb-container'><a class=\"maxbutton-103 maxbutton maxbutton-news-datatec\" href=\"https:\/\/messweb-masters.de\/?s=datatec\"><span class='mb-text'>Mehr von dataTec &gt;&gt;&gt;<\/span><\/a><\/span>\n","protected":false},"excerpt":{"rendered":"<p>Schulungen, Webinare, Herstellerworkshops \u2013 diese und weitere hochwertige Weiterbildungsangebote f\u00fchrt der neue digitale Eventkalender des Messtechnik-Distributors dataTec jetzt erstmals an einem Ort zusammen. Die kompakte Online-\u00dcbersicht l\u00e4sst sich nach Datum, Themenfeld und Format filtern und bietet die M\u00f6glichkeit, Termine direkt&#8230;<\/p>\n","protected":false},"author":4,"featured_media":52519,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-52516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/12\/dataTec-Eventkalender-300x150-1.jpg?fit=300%2C150&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8ayXV-dF2","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/52516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/comments?post=52516"}],"version-history":[{"count":7,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/52516\/revisions"}],"predecessor-version":[{"id":52525,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/52516\/revisions\/52525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media\/52519"}],"wp:attachment":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media?parent=52516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/categories?post=52516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/tags?post=52516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}