{"id":45434,"date":"2025-02-10T11:58:17","date_gmt":"2025-02-10T10:58:17","guid":{"rendered":"https:\/\/messweb-masters.de\/?p=45434"},"modified":"2025-11-11T15:59:58","modified_gmt":"2025-11-11T14:59:58","slug":"datatec-ausgezeichnet-mit-dem-flir-marketing-award","status":"publish","type":"post","link":"https:\/\/messweb-masters.de\/en\/datatec-ausgezeichnet-mit-dem-flir-marketing-award\/","title":{"rendered":"DATATEC: Ausgezeichnet mit dem FLIR Marketing-Award"},"content":{"rendered":"<p><strong><a href=\"https:\/\/messweb-masters.de\/aussteller\/profile\/datatec\/\"><img decoding=\"async\" class=\"logo alignright\" src=\"https:\/\/messweb-masters.de\/wp-content\/uploads\/2024\/03\/2024_dataTec_mClaim.svg\" \/><\/a>dataTec, Fachdistributor f\u00fcr Mess- und Pr\u00fcftechnik, wurde mit dem FLIR Marketing-Award ausgezeichnet. Diese besondere Ehrung wurde im Rahmen der EMEA Star Awards in Stockholm im Februar verliehen und von J\u00f6rg Scholl, Bereichsleitung Elektronische Mess- und Pr\u00fcftechnik DACH bei dataTec, entgegengenommen.<\/strong><\/p>\n<p>Flir w\u00fcrdigte mit dieser Auszeichnung insbesondere die hervorragende Zusammenarbeit in der Kommunikation f\u00fcr das Jahr 2024, ob auf Messen, im Printbereich oder den Online-Kan\u00e4len. \u201eInsbesondere die erfolgreichen gemeinsamen Messe-Auftritte im vergangenen Jahr, aber auch der neue Online-Shop mit seiner Kombination aus ansprechendem Design, benutzerfreundlicher Navigation und fachlich fundierten Inhalten werden mit diesem Award gew\u00fcrdigt\u201c, unterstreicht Andreas Angerer, Sales Manager bei Flir.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"45442\" data-permalink=\"https:\/\/messweb-masters.de\/en\/datatec_flir__marketing_award2_600x400\/\" data-orig-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/03\/dataTec_Flir__Marketing_Award2_600x400.jpg?fit=600%2C400&amp;ssl=1\" data-orig-size=\"600,400\" data-comments-opened=\"0\" data-image-title=\"dataTec_Flir__Marketing_Award2_600x400\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/03\/dataTec_Flir__Marketing_Award2_600x400.jpg?fit=600%2C400&amp;ssl=1\" class=\"alignright wp-image-45442\" src=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/03\/dataTec_Flir__Marketing_Award2_600x400.jpg?resize=300%2C200&#038;ssl=1\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/03\/dataTec_Flir__Marketing_Award2_600x400.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/03\/dataTec_Flir__Marketing_Award2_600x400.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/03\/dataTec_Flir__Marketing_Award2_600x400.jpg?resize=150%2C100&amp;ssl=1 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\nRoland Bertler (Bild), Bereichsleiter Marketing bei dataTec erg\u00e4nzt: \u201eWir freuen uns sehr \u00fcber diese Auszeichnung, die unsere hohen Qualit\u00e4tsstandards unterstreicht und das Engagement unseres gesamten Teams w\u00fcrdigt. Sie best\u00e4rkt uns darin, weiterhin die bestm\u00f6glichen L\u00f6sungen f\u00fcr unsere Partner wie FLIR und unsere Kunden zu entwickeln.\u201c Auch in Zukunft werden beide Unternehmen gemeinsame Konzepte entwickeln, um modernste Messtechnik einem breiten Spektrum an Anwendern n\u00e4herzubringen und so nachhaltige Gesch\u00e4ftsm\u00f6glichkeiten zu generieren.<\/p>\n<p><a href=\"https:\/\/www.datatec.eu\/\" target=\"_blank\" rel=\"noopener\">Mehr Informationen&#8230;<\/a><span class='maxbutton-103-container mb-container'><a class=\"maxbutton-103 maxbutton maxbutton-news-datatec\" href=\"https:\/\/messweb-masters.de\/?s=datatec\"><span class='mb-text'>Mehr von dataTec &gt;&gt;&gt;<\/span><\/a><\/span>\n","protected":false},"excerpt":{"rendered":"<p>dataTec, Fachdistributor f\u00fcr Mess- und Pr\u00fcftechnik, wurde mit dem FLIR Marketing-Award ausgezeichnet. Diese besondere Ehrung wurde im Rahmen der EMEA Star Awards in Stockholm im Februar verliehen und von J\u00f6rg Scholl, Bereichsleitung Elektronische Mess- und Pr\u00fcftechnik DACH bei dataTec, entgegengenommen&#8230;.<\/p>\n","protected":false},"author":4,"featured_media":45433,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[413,302,412,382],"class_list":["post-45434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte","tag-distributor","tag-messtechnik","tag-prueftechnik","tag-waermebildkamera"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2025\/03\/dataTec_Flir_Marketing_Award1_300x200.jpg?fit=300%2C200&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8ayXV-bOO","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/45434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/comments?post=45434"}],"version-history":[{"count":9,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/45434\/revisions"}],"predecessor-version":[{"id":52115,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/45434\/revisions\/52115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media\/45433"}],"wp:attachment":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media?parent=45434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/categories?post=45434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/tags?post=45434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}