{"id":31078,"date":"2023-07-11T16:31:52","date_gmt":"2023-07-11T14:31:52","guid":{"rendered":"https:\/\/messweb-masters.de\/?p=31078"},"modified":"2023-08-01T14:33:52","modified_gmt":"2023-08-01T12:33:52","slug":"pcb-synotech-komplette-sil2-messkette-fuer-die-prozessautomation","status":"publish","type":"post","link":"https:\/\/messweb-masters.de\/en\/pcb-synotech-komplette-sil2-messkette-fuer-die-prozessautomation\/","title":{"rendered":"PCB SYNOTECH: Komplette SIL2-Messkette f\u00fcr die Prozessautomation"},"content":{"rendered":"<p><strong><a href=\"https:\/\/messweb-masters.de\/aussteller\/profile\/synotech\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"logo alignright\" src=\"https:\/\/messweb-masters.de\/wp-content\/uploads\/2021\/07\/2021_PCB.svg\" alt=\"\"\/><\/a>Mit steigendem Risiko f\u00fcr Maschinensch\u00e4den sind h\u00f6here Anforderungen an die Sicherheit von sicherheitstechnischen Einrichtungen verbunden. Die Norm IEC\/DIN 61508 definiert vier Sicherheitsstufen, die Ma\u00dfnahmen zur Risikominimierung beschreiben. PCB Piezotronics, Inc. bietet hierzu Sensoren und Versorgungseinheiten an, welche die Klassifizierung SIL2 aufweisen.<\/strong><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"31077\" data-permalink=\"https:\/\/messweb-masters.de\/en\/pcb_pi23004_300x225\/\" data-orig-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/07\/PCB_PI23004_300x225.jpg?fit=300%2C225&amp;ssl=1\" data-orig-size=\"300,225\" data-comments-opened=\"0\" data-image-title=\"PCB_PI23004_300x225\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/07\/PCB_PI23004_300x225.jpg?fit=300%2C225&amp;ssl=1\" class=\"alignleft wp-image-31077\" src=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/07\/PCB_PI23004_300x225.jpg?resize=300%2C225&#038;ssl=1\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/07\/PCB_PI23004_300x225.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/07\/PCB_PI23004_300x225.jpg?resize=150%2C113&amp;ssl=1 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Zu nennen sind hier zum einen die Vibrationstransmitter der Serie 64x, welche entsprechend des Schwingpegels ein 4\u202620 mA-Ausgangssignal zur Verf\u00fcgung stellen. Zum anderen die ICP\u00ae\/IEPE-Beschleunigungssensoren der Serien 60x und 62x welche in Verbindung mit den Versorgungseinheiten der Serie 682 ebenfalls bewertete Ausgangssignale zur Verf\u00fcgung stellen.<\/p>\n<p>In Abh\u00e4ngigkeit der gew\u00e4hlten L\u00f6sung stehen am Ausgang die Schwinggeschwindigkeit oder Schwingbeschleunigung (beides RMS oder Peak), der W\u00e4lzlagerzustand und zus\u00e4tzlich das Schwingungsrohsignal, welches f\u00fcr die gezielte Schadensanalyse genutzt werden kann, zur Verf\u00fcgung.<\/p>\n<p>F\u00fcr s\u00e4mtliche vorgenannten Komponenten liegen die entsprechenden SIL2 Erkl\u00e4rungen vor. Zu finden im Downloadbereich der Webseite, alternativ per E-Mail anfordern.<\/p>\n<p><a href=\"https:\/\/www.pcbpiezotronics.de\/blog\/artikel\/2019\/03\/22\/sil-zertifizierte-schwingungssensoren\" target=\"_blank\" rel=\"noopener noreferrer\">Mehr Informationen&#8230;<\/a><\/p>\n<p><strong>Besuchen Sie uns beim messweb masters an unserem neuen Stand Nr. 6A.<\/strong><span class='maxbutton-48-container mb-container'><a class=\"maxbutton-48 maxbutton maxbutton-weitere-produkte-pcb\" href=\"https:\/\/messweb-masters.de\/category\/produkte\/?s=pcb\"><span class='mb-text'>Weitere Produkte &gt;&gt;&gt;<\/span><\/a><\/span>\n","protected":false},"excerpt":{"rendered":"<p>Mit steigendem Risiko f\u00fcr Maschinensch\u00e4den sind h\u00f6here Anforderungen an die Sicherheit von sicherheitstechnischen Einrichtungen verbunden. Die Norm IEC\/DIN 61508 definiert vier Sicherheitsstufen, die Ma\u00dfnahmen zur Risikominimierung beschreiben. PCB Piezotronics, Inc. bietet hierzu Sensoren und Versorgungseinheiten an, welche die Klassifizierung SIL2&#8230;<\/p>\n","protected":false},"author":4,"featured_media":31077,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[121,169,170,339,343,30],"class_list":["post-31078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte","tag-beschleunigungssensor","tag-icp","tag-iepe","tag-schwingungssensoren","tag-sil2","tag-vibration"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/07\/PCB_PI23004_300x225.jpg?fit=300%2C225&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8ayXV-85g","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/31078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/comments?post=31078"}],"version-history":[{"count":8,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/31078\/revisions"}],"predecessor-version":[{"id":31086,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/31078\/revisions\/31086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media\/31077"}],"wp:attachment":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media?parent=31078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/categories?post=31078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/tags?post=31078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}