{"id":30679,"date":"2023-05-08T10:07:42","date_gmt":"2023-05-08T08:07:42","guid":{"rendered":"https:\/\/messweb-masters.de\/?p=30679"},"modified":"2023-09-21T09:22:15","modified_gmt":"2023-09-21T07:22:15","slug":"ipetronik-ipemotion-2023-r1-jetzt-mit-online-leistungsberechnung","status":"publish","type":"post","link":"https:\/\/messweb-masters.de\/en\/ipetronik-ipemotion-2023-r1-jetzt-mit-online-leistungsberechnung\/","title":{"rendered":"IPETRONIK: IPEmotion 2023 R1 jetzt mit Online-Leistungsberechnung"},"content":{"rendered":"<p><a href=\"https:\/\/messweb-masters.de\/aussteller\/profile\/ipetronik\/\"><img loading=\"lazy\" decoding=\"async\" class=\"logo alignright\" src=\"https:\/\/messweb-masters.de\/wp-content\/uploads\/logo\/2018-IPEtronik.svg\" alt=\"\" width=\"116\" height=\"58\"><\/a><strong>Das neue Release IPEmotion 2023 R1 bietet eine Vielzahl an neuen Features. Zu den wichtigsten Neuerungen geh\u00f6rt die neue Funktion \u201eOnline-Leistungsberechnung\u201c, die die Nutzung vordefinierter Leistungsberechnungen f\u00fcr Messaufgaben und Datenanalysen erm\u00f6glicht. Dar\u00fcber hinaus unterst\u00fctzt IPEmotion 2023 R1 nun auch einen neuen Speichermodus zum Erzeugen von Snapshot-Daten. Zudem wurde die Traffic-to-Signal Funktion verbessert.<\/strong><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"30682\" data-permalink=\"https:\/\/messweb-masters.de\/en\/ipemotion_2023_r1_200x150\/\" data-orig-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/05\/IPEmotion_2023_R1_200x150.jpg?fit=200%2C150&amp;ssl=1\" data-orig-size=\"200,150\" data-comments-opened=\"0\" data-image-title=\"IPEmotion_2023_R1_200x150\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/05\/IPEmotion_2023_R1_200x150.jpg?fit=200%2C150&amp;ssl=1\" class=\"wp-image-30682 alignright\" src=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/05\/IPEmotion_2023_R1_200x150.jpg?resize=200%2C150&#038;ssl=1\" alt=\"\" width=\"200\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/05\/IPEmotion_2023_R1_200x150.jpg?w=200&amp;ssl=1 200w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/05\/IPEmotion_2023_R1_200x150.jpg?resize=150%2C113&amp;ssl=1 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n<p>Die Neuheiten im \u00dcberblick::<\/p>\n<p><strong>Neue Funktion \u201eOnline-Leistungsberechnung\u201c<\/strong><\/p>\n<ul>\n<li>Einfache Auswahl der Eingangskan\u00e4le f\u00fcr Spannung und Strom<\/li>\n<li>Netzfrequenz kann auf einen festen Wert eingestellt werden oder automatisch von IPEmotion ermittelt werden<\/li>\n<li>Verf\u00fcgbar als Online-Berechnung (Reiter &#8220;Acquisition&#8221;) oder als Offline-Berechnung (Reiter &#8220;Datenverwaltung&#8221;)<\/li>\n<\/ul>\n<p><strong>Neuer Speichermodus \u201eMomentaufnahmen-Speicherung\u201c f\u00fcr Speichergruppen<\/strong><\/p>\n<ul>\n<li>Konfigurierbarer Snapshot-Trigger<\/li>\n<li>Mehrere Snapshots sind m\u00f6glich<\/li>\n<li>Alle unterst\u00fctzten Speicherformate k\u00f6nnen verwendet werden: IPEmotion, MDF4 und MDF4 gruppiert<\/li>\n<\/ul>\n<p><strong>Traffic-to-Signal Verbesserungen<\/strong><\/p>\n<ul>\n<li>Die &#8220;Konverter&#8221;-Funktion in IPEmotion unterst\u00fctzt nun Traffic-to-Signal, Profile und Kanalfilter<\/li>\n<li>Mehrere Traffic-Kan\u00e4le aus mehreren Messdateien k\u00f6nnen in einem Schritt in Signale umgewandelt werden<\/li>\n<li>Die M\u00f6glichkeit, Profile zu erstellen, wurde mit IPEmotion 2022 R3 eingef\u00fchrt. Diese Profile k\u00f6nnen auch in der &#8220;Konverter&#8221;-Funktion verwendet werden.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.ipetronik.com\/de\/neuigkeiten-aktuelles\/details\/ipemotion-2023-r1-unterstuetzt-nun-auch-online-leistungsberechnung.html\" target=\"_blank\" rel=\"noopener noreferrer\">Mehr erfahren Sie auf unserer Webseite&#8230;<\/a><span class='maxbutton-56-container mb-container'><a class=\"maxbutton-56 maxbutton maxbutton-weitere-produkte-ipetronik\" href=\"https:\/\/messweb-masters.de\/category\/produkte\/?s=ipetronik\"><span class='mb-text'>Weitere Produkte &gt;&gt;&gt;<\/span><\/a><\/span>\n","protected":false},"excerpt":{"rendered":"<p>Das neue Release IPEmotion 2023 R1 bietet eine Vielzahl an neuen Features. Zu den wichtigsten Neuerungen geh\u00f6rt die neue Funktion \u201eOnline-Leistungsberechnung\u201c, die die Nutzung vordefinierter Leistungsberechnungen f\u00fcr Messaufgaben und Datenanalysen erm\u00f6glicht. Dar\u00fcber hinaus unterst\u00fctzt IPEmotion 2023 R1 nun auch einen&#8230;<\/p>\n","protected":false},"author":4,"featured_media":30682,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[69,28],"class_list":["post-30679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte","tag-leistungsmessung","tag-software"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/05\/IPEmotion_2023_R1_200x150.jpg?fit=200%2C150&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8ayXV-7YP","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/30679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/comments?post=30679"}],"version-history":[{"count":9,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/30679\/revisions"}],"predecessor-version":[{"id":32051,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/30679\/revisions\/32051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media\/30682"}],"wp:attachment":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media?parent=30679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/categories?post=30679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/tags?post=30679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}