{"id":30525,"date":"2023-03-15T18:10:00","date_gmt":"2023-03-15T17:10:00","guid":{"rendered":"https:\/\/messweb-masters.de\/?p=30525"},"modified":"2024-01-31T17:57:28","modified_gmt":"2024-01-31T16:57:28","slug":"althen-neue-energien-effizienter-erzeugen","status":"publish","type":"post","link":"https:\/\/messweb-masters.de\/en\/althen-neue-energien-effizienter-erzeugen\/","title":{"rendered":"ALTHEN: Neue Energien effizienter erzeugen"},"content":{"rendered":"<p><strong><a href=\"https:\/\/messweb-masters.de\/aussteller\/profile\/althen-mess-sensortechnik\/\"><img loading=\"lazy\" decoding=\"async\" class=\"logo alignright\" src=\"https:\/\/messweb-masters.de\/wp-content\/uploads\/logo\/2018-ALTHEN.svg\" width=\"116\" height=\"58\"><\/a>Der Markt f\u00fcr erneuerbare Energien ist in Bewegung: Solar- und Windkraftanlagen werden immer weiter ausgebaut, neue Technologien forciert. Zuverl\u00e4ssige und ma\u00dfgeschneiderte Messtechnik und Sensorik sind gerade in diesen Anwendungsbereichen von Bedeutung.<\/strong><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"30528\" data-permalink=\"https:\/\/messweb-masters.de\/en\/althen_neueenergien_300x199\/\" data-orig-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/04\/Althen_NeueEnergien_300x199.jpg?fit=300%2C199&amp;ssl=1\" data-orig-size=\"300,199\" data-comments-opened=\"0\" data-image-title=\"Althen_NeueEnergien_300x199\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/04\/Althen_NeueEnergien_300x199.jpg?fit=300%2C199&amp;ssl=1\" class=\"alignleft wp-image-30528\" src=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/04\/Althen_NeueEnergien_300x199.jpg?resize=300%2C199&#038;ssl=1\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/04\/Althen_NeueEnergien_300x199.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/04\/Althen_NeueEnergien_300x199.jpg?resize=150%2C100&amp;ssl=1 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Beschleunigungssensoren sind f\u00fcr die \u00dcberwachung und Wartung von Windkraftanlagen sehr n\u00fctzlich, denn an Rotorbl\u00e4ttern k\u00f6nnen aerodynamische und massebedingte Unwuchten entstehen, die sich negativ auf die Performance und Effizienz der Anlage auswirken. Abhilfe schaffen beispielsweise Beschleunigungsaufnehmer wie der ASC 5511LN und ASC 5515 LN, die z.B. im Maschinentr\u00e4ger der Gondel verbaut werden. Dank ihres kapazitiven Messprinzips auf Basis hochwertiger MEMS (mikro-elektronisch-mechanische Systeme) und des sehr guten Signal-Rausch-Verh\u00e4ltnisses erfassen sie die niedrigen Rotordrehfrequenzen von Windr\u00e4dern sehr pr\u00e4zise. Ein weiterer Vorteil dieser Beschleunigungssensoren ist die integrierte Signalverst\u00e4rkung, die direkt von der Ausleseelektronik weiterverarbeitet werden kann.<\/p>\n<p><strong>H\u00f6here Schutzart f\u00fcr den Au\u00dfeneinsatz<\/strong><br \/>\nInteressant f\u00fcr den Au\u00dfeneinsatz, auch unter widrigen Witterungsbedingungen, sind Sensoren mit hermetisch verschwei\u00dftem Geh\u00e4use mit h\u00f6herer Schutzklasse IP68. Ein Beispiel ist die OS-Serie von ASC, die Althen ebenfalls im Programm hat. F\u00fcr Testanwendungen bei der Entwicklung neuer Windr\u00e4der wurden die ASC-OS-Beschleunigungssensoren am Fundament einer Anlage montiert, um zu ermitteln, inwieweit sich die Drehbewegung der Rotorbl\u00e4tter auf das Fundament \u00fcbertr\u00e4gt und dort zu Verschlei\u00df f\u00fchrt. Hierf\u00fcr wurde die Vibration bzw. Bewegung in x\/y-Richtung detektiert.<\/p>\n<p><strong>Kundenindividuelle Anpassungen und Service<\/strong><br \/>\nF\u00fcr alle Sensoren und Messsysteme im Portfolio gilt, dass die Messspezialisten von Althen kundenindividuelle Anpassungen je nach Anwendung vornehmen k\u00f6nnen und auch bei der Konstruktion, Inbetriebnahme, Kalibrierung oder technischen Problemen unterst\u00fctzen.<\/p>\n<p><a href=\"https:\/\/www.althensensors.com\/de\/presse-events\/neue-energien-effizienter-erzeugen\/\" target=\"_blank\" rel=\"noopener\">Mehr Informationen&#8230;<\/a><br \/>\n<span class='maxbutton-53-container mb-container'><a class=\"maxbutton-53 maxbutton maxbutton-weitere-produkte-althen\" href=\"https:\/\/messweb-masters.de\/category\/produkte\/?s=althen\"><span class='mb-text'>Weitere Produkte &gt;&gt;&gt;<\/span><\/a><\/span>\n","protected":false},"excerpt":{"rendered":"<p>Der Markt f\u00fcr erneuerbare Energien ist in Bewegung: Solar- und Windkraftanlagen werden immer weiter ausgebaut, neue Technologien forciert. Zuverl\u00e4ssige und ma\u00dfgeschneiderte Messtechnik und Sensorik sind gerade in diesen Anwendungsbereichen von Bedeutung. Beschleunigungssensoren sind f\u00fcr die \u00dcberwachung und Wartung von Windkraftanlagen&#8230;<\/p>\n","protected":false},"author":4,"featured_media":30528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[121,202,17,30,338],"class_list":["post-30525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte","tag-beschleunigungssensor","tag-ip68","tag-sensoren","tag-vibration","tag-windenergie"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2023\/04\/Althen_NeueEnergien_300x199.jpg?fit=300%2C199&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8ayXV-7Wl","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/30525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/comments?post=30525"}],"version-history":[{"count":9,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/30525\/revisions"}],"predecessor-version":[{"id":33340,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/30525\/revisions\/33340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media\/30528"}],"wp:attachment":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media?parent=30525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/categories?post=30525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/tags?post=30525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}