{"id":26387,"date":"2022-03-25T17:28:53","date_gmt":"2022-03-25T16:28:53","guid":{"rendered":"https:\/\/messweb-masters.de\/?p=26387"},"modified":"2022-03-25T17:28:54","modified_gmt":"2022-03-25T16:28:54","slug":"pcb-synotech-triaxialer-miniatur-icp-beschleunigungssensor-mit-stecker-mit-hoher-empfindlichkeit","status":"publish","type":"post","link":"https:\/\/messweb-masters.de\/en\/pcb-synotech-triaxialer-miniatur-icp-beschleunigungssensor-mit-stecker-mit-hoher-empfindlichkeit\/","title":{"rendered":"PCB SYNOTECH: Triaxialer Miniatur-ICP\u00ae-Beschleunigungssensor mit Stecker mit hoher Empfindlichkeit"},"content":{"rendered":"<p><strong><a href=\"https:\/\/messweb-masters.de\/aussteller\/profile\/synotech\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"logo alignright\" src=\"https:\/\/messweb-masters.de\/wp-content\/uploads\/2021\/07\/2021_PCB.svg\" alt=\"\" \/><\/a>Das Modell 356A09 von PCB Piezotronics bietet bei einer Empfindlichkeit von 10mV\/g einen Messbereich von 500 g und einen weiten Frequenzbereich von 8 kHz (\u00b15 %) f\u00fcr viele Arten von Vibrationstests.<\/strong><\/p>\n<p>Die hohe Schockfestigkeit und das hermetisch dichte Titangeh\u00e4use machen den Sensor trotz seiner kleinen Abmessungen \u00e4u\u00dferst robust. Mit einem Gewicht von nur 1 Gramm und einer Kantenl\u00e4nge von nur 6,3 mm eignet sich der Sensor auch hervorragend f\u00fcr Messungen an kleinen Bauteilen und verhindert Mass-Loading-Effekte.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"26389\" data-permalink=\"https:\/\/messweb-masters.de\/en\/pcb-synotech-triaxialer-miniatur-icp-beschleunigungssensor-mit-stecker-mit-hoher-empfindlichkeit\/pcb_pi22022\/\" data-orig-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2022\/03\/PCB_PI22022.jpg?fit=377%2C368&amp;ssl=1\" data-orig-size=\"377,368\" data-comments-opened=\"0\" data-image-title=\"PCB_PI22022\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2022\/03\/PCB_PI22022.jpg?fit=377%2C368&amp;ssl=1\" class=\"wp-image-26389 size-medium alignleft\" src=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2022\/03\/PCB_PI22022.jpg?resize=300%2C293&#038;ssl=1\" alt=\"\" width=\"300\" height=\"293\" srcset=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2022\/03\/PCB_PI22022.jpg?resize=300%2C293&amp;ssl=1 300w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2022\/03\/PCB_PI22022.jpg?resize=150%2C146&amp;ssl=1 150w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2022\/03\/PCB_PI22022.jpg?w=377&amp;ssl=1 377w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Dank des Mini-4-Pin-Steckers ist das Kabel einfach vom Sensor zu l\u00f6sen und die Klebemontage wird vereinfacht. Auch lassen sich unterschiedliche Kabel, abh\u00e4ngig vom jeweiligen Einsatzzweck, verwenden, wie z.B. das besonders leichte und flexible Messkabel der Serie 019 mit Silikonmantel.<\/p>\n<p>PCB\u00ae bietet aus dieser Reihe von triaxialen Miniatur-Beschleunigungssensoren neben den Steckerversionen auch Modelle mit integriertem Kabel sowie Messbereich 1000 g (Model 356A06), Hochtemperaturausf\u00fchrungen bis 180 \u00b0 Dauereinsatztemperatur, Masseisolierung sowie wasser- und \u00f6ldichte Kabelausf\u00fchrung.<\/p>\n<p>Weitere Informationen unter <a href=\"https:\/\/www.synotech.de\/356A09\" target=\"_blank\" rel=\"noopener\">www.synotech.de\/356A09<\/a><\/p>\n<p><strong>Besuchen Sie uns beim messweb masters an unserem Stand Nr. 2A.<\/strong><span class='maxbutton-48-container mb-container'><a class=\"maxbutton-48 maxbutton maxbutton-weitere-produkte-pcb\" href=\"https:\/\/messweb-masters.de\/category\/produkte\/?s=pcb\"><span class='mb-text'>Weitere Produkte &gt;&gt;&gt;<\/span><\/a><\/span>\n","protected":false},"excerpt":{"rendered":"<p>Das Modell 356A09 von PCB Piezotronics bietet bei einer Empfindlichkeit von 10mV\/g einen Messbereich von 500 g und einen weiten Frequenzbereich von 8 kHz (\u00b15 %) f\u00fcr viele Arten von Vibrationstests. Die hohe Schockfestigkeit und das hermetisch dichte Titangeh\u00e4use machen&#8230;<\/p>\n","protected":false},"author":4,"featured_media":26389,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[121,169,170,184,312],"class_list":["post-26387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte","tag-beschleunigungssensor","tag-icp","tag-iepe","tag-miniatur","tag-triaxial"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2022\/03\/PCB_PI22022.jpg?fit=377%2C368&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8ayXV-6RB","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/26387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/comments?post=26387"}],"version-history":[{"count":23,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/26387\/revisions"}],"predecessor-version":[{"id":26411,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/26387\/revisions\/26411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media\/26389"}],"wp:attachment":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media?parent=26387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/categories?post=26387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/tags?post=26387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}