{"id":17854,"date":"2020-08-27T10:34:39","date_gmt":"2020-08-27T08:34:39","guid":{"rendered":"https:\/\/messtec-masters.de\/?p=17854"},"modified":"2020-11-13T11:05:15","modified_gmt":"2020-11-13T10:05:15","slug":"imc-digitale-1-kanal-telemetrie-fuer-rotierende-wellen","status":"publish","type":"post","link":"https:\/\/messweb-masters.de\/en\/imc-digitale-1-kanal-telemetrie-fuer-rotierende-wellen\/","title":{"rendered":"IMC: Digitale 1-Kanal-Telemetrie f\u00fcr rotierende Wellen"},"content":{"rendered":"<p><strong><a href=\"https:\/\/messtec-masters.de\/aussteller\/profile\/imc-tm-gmbh\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"logo alignright\" title=\"imc Test &amp; Measurement\" src=\"https:\/\/messtec-masters.de\/wp-content\/uploads\/logo\/2018-imc.svg\" alt=\"\" width=\"191\" height=\"87\"><\/a>Das 1-Kanal-Telemetriesystem T1 ist ideal zur drahtlosen \u00dcbertragung von DMS-Signalen von rotierenden Wellen. Die Sendeelektronik erlaubt den direkten Anschluss von Dehnmessstreifen im Voll- und Halbbr\u00fcckenmodus. Die Br\u00fcckenspeisung betr\u00e4gt fest 4 Volt DC und die Verst\u00e4rkung kann in 4 Stufen frei gew\u00e4hlt werden. Die Sendeelektronik (Encoder) ist lediglich 35 mm breit, 18 mm lang und 12 mm tief und wiegt nur 13 Gramm.<\/strong><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17856\" data-permalink=\"https:\/\/messweb-masters.de\/en\/imc-digitale-1-kanal-telemetrie-fuer-rotierende-wellen\/t1-pcm-stg-finger\/\" data-orig-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2020\/09\/T1-PCM-STG-Finger.jpg?fit=480%2C347&amp;ssl=1\" data-orig-size=\"480,347\" data-comments-opened=\"0\" data-image-title=\"T1-PCM-STG-Finger\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2020\/09\/T1-PCM-STG-Finger.jpg?fit=480%2C347&amp;ssl=1\" class=\"alignleft wp-image-17856 size-medium\" src=\"https:\/\/i0.wp.com\/messtec-masters.de\/wp-content\/uploads\/2020\/09\/T1-PCM-STG-Finger-300x217.jpg?resize=300%2C217&#038;ssl=1\" alt=\"\" width=\"300\" height=\"217\" srcset=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2020\/09\/T1-PCM-STG-Finger.jpg?resize=300%2C217&amp;ssl=1 300w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2020\/09\/T1-PCM-STG-Finger.jpg?resize=150%2C108&amp;ssl=1 150w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2020\/09\/T1-PCM-STG-Finger.jpg?w=480&amp;ssl=1 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><strong>Einfache Installation<\/strong><br \/>\nDer Sender l\u00e4sst sich entweder mittels eines speziellen glasfaserverst\u00e4rkten Tapes in Minuten auf der Welle befestigen oder wird direkt in einem f\u00fcr die Welle angefertigten Ringgeh\u00e4use verbaut.<\/p>\n<p><strong>Drahtlose \u00dcbertragung und Versorgung<\/strong><br \/>\nDie Versorgung der Sendeseite und die digitale Daten\u00fcbertragung zum Empf\u00e4nger erfolgen induktiv. Der T1-Encoder erzeugt mittels Pulse-Code-Modulation ein digitales Signal (PCM), das \u00fcber eine Induktionswicklung um die Welle zum Empfangskopf \u00fcbertragen wird. Von dort wird das Signal \u00fcber Kabel zur Empfangseinheit gesendet. Der maximale Abstand zwischen der Sendespule und dem Empfangs-Versorgungskopf betr\u00e4gt bis zu 35 mm.<\/p>\n<p>Die Empfangseinheit bietet standardm\u00e4\u00dfig auf der Frontseite einen Analogausgang (+\/- 10 V) und kann zus\u00e4tzlich auch mit einem Stromausgang (4 &#8230; 20 mA) ausgestattet werden. Ein automatischer Nullabgleich (Autozero) kann durch Dr\u00fccken des AZ-Knopfes auf der Frontseite des Empf\u00e4ngers ausgel\u00f6st werden.<\/p>\n<p><a href=\"https:\/\/www.imc-tm.de\/produkte\/sensorik-loesungen\/telemetrie\/t1-digitale-1-kanal-telemetrie\/\" target=\"_blank\" rel=\"noopener noreferrer\">Weitere Informationen finden Sie hier.<\/a><span class='maxbutton-51-container mb-container'><a class=\"maxbutton-51 maxbutton maxbutton-weitere-produkte-imc\" href=\"https:\/\/messweb-masters.de\/category\/produkte\/?s=IMC:\"><span class='mb-text'>Weitere Produkte &gt;&gt;&gt;<\/span><\/a><\/span>\n","protected":false},"excerpt":{"rendered":"<p>Das 1-Kanal-Telemetriesystem T1 ist ideal zur drahtlosen \u00dcbertragung von DMS-Signalen von rotierenden Wellen. Die Sendeelektronik erlaubt den direkten Anschluss von Dehnmessstreifen im Voll- und Halbbr\u00fcckenmodus. Die Br\u00fcckenspeisung betr\u00e4gt fest 4 Volt DC und die Verst\u00e4rkung kann in 4 Stufen frei&#8230;<\/p>\n","protected":false},"author":4,"featured_media":17856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[31,233,16],"class_list":["post-17854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte","tag-dms","tag-pcm","tag-telemetrie"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2020\/09\/T1-PCM-STG-Finger.jpg?fit=480%2C347&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8ayXV-4DY","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/17854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/comments?post=17854"}],"version-history":[{"count":26,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/17854\/revisions"}],"predecessor-version":[{"id":18576,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/17854\/revisions\/18576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media\/17856"}],"wp:attachment":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media?parent=17854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/categories?post=17854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/tags?post=17854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}