{"id":15150,"date":"2020-05-18T16:15:04","date_gmt":"2020-05-18T14:15:04","guid":{"rendered":"https:\/\/messtec-masters.de\/?p=15150"},"modified":"2020-06-15T12:43:33","modified_gmt":"2020-06-15T10:43:33","slug":"manner-neue-miniatur-sensortelemetrie-fur-prufstands-und-validierungsaufgaben-am-fahrzeug","status":"publish","type":"post","link":"https:\/\/messweb-masters.de\/en\/manner-neue-miniatur-sensortelemetrie-fur-prufstands-und-validierungsaufgaben-am-fahrzeug\/","title":{"rendered":"MANNER: Neue Miniatur-Sensortelemetrie f\u00fcr Pr\u00fcf- und Validierungsaufgaben am Fahrzeug"},"content":{"rendered":"<p><a href=\"https:\/\/messtec-masters.de\/aussteller\/profile\/manner\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"logo alignright\" title=\"Manner Sensortelemetrie GmbH\" src=\"https:\/\/messtec-masters.de\/wp-content\/uploads\/2019\/12\/2020_Manner.svg\" alt=\"(Bild fehlt)\"><\/a><strong>MANNER Sensortelemetrie bietet ein umfangreiches Portfolio f\u00fcr Pr\u00fcfstands-, Validierungs- und Wirkungsgradanalyseaufgaben. Durch die Weiterentwicklung der MANNER Messtechnologie wurde eine neue Miniatur-Verst\u00e4rkertechnologie entwickelt, die ein- und mehrkanalig im Miniaturformat dynamische Bauteilbelastungsmessungen \/ Drehmomenterfassungen mit einer Bandbreite von bis zu 10 kHz erm\u00f6glicht.<\/strong><\/p>\n<div id=\"attachment_15158\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/messtec-masters.de\/wp-content\/uploads\/2020\/05\/Manner_04.jpg?ssl=1\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-15158\" data-attachment-id=\"15158\" data-permalink=\"https:\/\/messweb-masters.de\/en\/manner-neue-miniatur-sensortelemetrie-fur-prufstands-und-validierungsaufgaben-am-fahrzeug\/manner_04\/\" data-orig-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2020\/05\/Manner_04.jpg?fit=531%2C344&amp;ssl=1\" data-orig-size=\"531,344\" data-comments-opened=\"0\" data-image-title=\"Manner_04\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;E-Motor Applikation mit 8 kompensierbaren Kan\u00e4len&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2020\/05\/Manner_04.jpg?fit=531%2C344&amp;ssl=1\" class=\"wp-image-15158 size-medium\" src=\"https:\/\/i0.wp.com\/messtec-masters.de\/wp-content\/uploads\/2020\/05\/Manner_04-300x194.jpg?resize=300%2C194&#038;ssl=1\" alt=\"\" width=\"300\" height=\"194\" srcset=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2020\/05\/Manner_04.jpg?resize=300%2C194&amp;ssl=1 300w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2020\/05\/Manner_04.jpg?resize=150%2C97&amp;ssl=1 150w, https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2020\/05\/Manner_04.jpg?w=531&amp;ssl=1 531w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-15158\" class=\"wp-caption-text\">E-Motor Applikation mit 8 kompensierbaren Kan\u00e4len<\/p><\/div>\n<p>Die Sensorsignalverst\u00e4rkerzellen k\u00f6nnen zu mehrkanaligen Systemen mit nahezu beliebigen Formfaktoren zusammen geschaltet werden. Die neue Verst\u00e4rkergeneration ist wie gewohnt als flexible und starre Ausf\u00fchrung erh\u00e4ltlich. Damit k\u00f6nnen selbst komplexe Messwerterfassungssysteme in beliebigen vorgegeben Baur\u00e4umen realisiert werden.<\/p>\n<p>Die flexible modulare Verst\u00e4rkertechnologie hat neben der Remote Control Funktion (Auto Zero; Verst\u00e4rkungseinstellung; Memory und andere Online Health Funktionen) auch die M\u00f6glichkeit Nullstellen- und E-Modulkompensationen \u2013 in Echtzeit w\u00e4hrend der Messung auszuf\u00fchren. Damit kann die Messgenauigkeit erheblich gesteigert werden. Messfehler durch Materialeigenschaften und Umwelteinfl\u00fcsse wie Nullpunktdrift und Temperaturabh\u00e4ngigkeit des E-Moduls (ca. 2,5% \/100\u00b0C) k\u00f6nnen damit auf nahezu Null reduziert werden.<\/p>\n<p>Der starre Zweikanalverst\u00e4rker mit DMS- und Temperaturkanal on Board hat die miniaturisierten Abmessungen von 6 mm x 24,8 mm x 3,5 mm, wodurch selbst die Integration in kompakte Designs ohne gro\u00dfe Anpassungen des Originalteils oder Unwuchten m\u00f6glich wird.<\/p>\n<p>Die flexible Ausf\u00fchrung des neuen Miniaturverst\u00e4rkers ist in zwei Ausf\u00fchrungen erh\u00e4ltlich. F\u00fcr die Eigenapplikation kann der Verst\u00e4rker mit einem integrierten Auto-Abgleichmodul verwendet werden. Hierdurch entf\u00e4llt jeglicher h\u00e4ndischer Abgleichaufwand f\u00fcr den Rotorantennenabgleich und die Applikation wird zur Plug &amp; Play Anwendung. Wenn der Messk\u00f6rper besonders kleine Durchmesser aufweist bzw. die Platzverh\u00e4ltnisse diese Komfortfunktion nicht zulassen, so ist der hochwertige Messverst\u00e4rker auch im Format 45,6 mm x 10 mm (mit Auto-Abgleich: 64 mm x 10 mm) erh\u00e4ltlich.<\/p>\n<p>Die neue Verst\u00e4rkergeneration bietet damit neue Integrations- und Messm\u00f6glichkeiten f\u00fcr jegliche Automotive Testing Anforderung. Beispielhafte Applikationen f\u00fcr diese neue Verst\u00e4rkergeneration sind Kupplungen, Riemenscheiben, Flexplates oder der Elektromotor.<\/p>\n<p><strong>Wir freuen uns auf Ihren Besuch an unserem Stand Nr. 4\/B!<\/strong><br \/>\n<a href=\"http:\/\/www.sensortelemetrie.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.sensortelemetrie.de<\/a><br \/>\n<span class='maxbutton-45-container mb-container'><a class=\"maxbutton-45 maxbutton maxbutton-weitere-produkte-manner\" href=\"https:\/\/messweb-masters.de\/category\/produkte\/?s=manner\"><span class='mb-text'>Weitere Produkte &gt;&gt;&gt;<\/span><\/a><\/span>\n","protected":false},"excerpt":{"rendered":"<p>MANNER Sensortelemetrie bietet ein umfangreiches Portfolio f\u00fcr Pr\u00fcfstands-, Validierungs- und Wirkungsgradanalyseaufgaben. Durch die Weiterentwicklung der MANNER Messtechnologie wurde eine neue Miniatur-Verst\u00e4rkertechnologie entwickelt, die ein- und mehrkanalig im Miniaturformat dynamische Bauteilbelastungsmessungen \/ Drehmomenterfassungen mit einer Bandbreite von bis zu 10 kHz&#8230;<\/p>\n","protected":false},"author":4,"featured_media":15155,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[31,41,53,42,16,93],"class_list":["post-15150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte","tag-dms","tag-e-mobilitat","tag-mobile-messtechnik","tag-prufstand","tag-telemetrie","tag-temperatur"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2020\/05\/Manner_03.jpg?fit=613%2C408&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8ayXV-3Wm","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/15150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/comments?post=15150"}],"version-history":[{"count":28,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/15150\/revisions"}],"predecessor-version":[{"id":15193,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/15150\/revisions\/15193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media\/15155"}],"wp:attachment":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media?parent=15150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/categories?post=15150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/tags?post=15150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}