{"id":10672,"date":"2019-02-04T12:05:31","date_gmt":"2019-02-04T11:05:31","guid":{"rendered":"http:\/\/messtec-masters.de\/?p=10672"},"modified":"2024-01-31T18:32:48","modified_gmt":"2024-01-31T17:32:48","slug":"althen-grosses-portfolio-an-beschleunigungssensoren","status":"publish","type":"post","link":"https:\/\/messweb-masters.de\/en\/althen-grosses-portfolio-an-beschleunigungssensoren\/","title":{"rendered":"ALTHEN: Gro\u00dfes Portfolio an Beschleunigungssensoren"},"content":{"rendered":"<p><strong><a href=\"https:\/\/messweb-masters.de\/aussteller\/profile\/althen-mess-sensortechnik\/\"><img loading=\"lazy\" decoding=\"async\" class=\"logo alignright\" src=\"https:\/\/messweb-masters.de\/wp-content\/uploads\/logo\/2018-ALTHEN.svg\" width=\"116\" height=\"58\"><\/a>Beschleunigungssensoren dienen der Messung von Vibrationen, St\u00f6\u00dfen, Verschiebungen, Geschwindigkeiten und Neigungen in vielen Pr\u00e4zisionsanwendungen. Althen bietet ein aktuelles Programm an zertifizierten, miniaturisierten Beschleunigungsaufnehmern.<\/strong><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"10379\" data-permalink=\"https:\/\/messweb-masters.de\/en\/althen-gl7000-ein-klassiker-mit-neuen-funktionen\/althen_gl7000\/\" data-orig-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2019\/01\/ALTHEN_GL7000.jpg?fit=700%2C467&amp;ssl=1\" data-orig-size=\"700,467\" data-comments-opened=\"0\" data-image-title=\"ALTHEN_GL7000\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2019\/01\/ALTHEN_GL7000.jpg?fit=700%2C467&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/messtec-masters.de\/wp-content\/uploads\/2019\/02\/ALTHEN_Programm_Beschleunigungssensoren.jpg?resize=300%2C200&#038;ssl=1\" alt=\"\" class=\"alignleft size-medium wp-image-10379\" width=\"300\" height=\"200\"><\/p>\n<p>Neben der Euro-NCAP-Zertifizierung sind Teile des Programms f\u00fcr den Crash-Testeinsatz auch nach SAE J211\/J2570, ISO 6487 und World SID zertifiziert. Die Sensoren sind sowohl einachsig- als auch triaxial-messend und stehen in verschiedenen Versionen zur Verf\u00fcgung. So k\u00f6nnen Kunden zwischen einer Variante mit integriertem Messverst\u00e4rker oder offener Wheatstone\u2019scher Vollbr\u00fccke w\u00e4hlen.<\/p>\n<p>Zur Disposition stehen auch Sensoren mit fest angebautem, geschirmtem und rauscharmem Kabel. Varianten mit Steckverbindern runden das umfangreiche Portfolio ab.<\/p>\n<p>Weitere Informationen unter <a href=\"https:\/\/www.althensensors.com\/de\" target=\"_blank\" rel=\"noopener\">www.althensensors.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beschleunigungssensoren dienen der Messung von Vibrationen, St\u00f6\u00dfen, Verschiebungen, Geschwindigkeiten und Neigungen in vielen Pr\u00e4zisionsanwendungen. Althen bietet ein aktuelles Programm an zertifizierten, miniaturisierten Beschleunigungsaufnehmern. Neben der Euro-NCAP-Zertifizierung sind Teile des Programms f\u00fcr den Crash-Testeinsatz auch nach SAE J211\/J2570, ISO 6487 und&#8230;<\/p>\n","protected":false},"author":4,"featured_media":10674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[25,17],"class_list":["post-10672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte","tag-beschleunigung","tag-sensoren"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/messweb-masters.de\/wp-content\/uploads\/2019\/02\/ALTHEN_Programm_Beschleunigungssensoren.jpg?fit=700%2C525&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8ayXV-2M8","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/10672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/comments?post=10672"}],"version-history":[{"count":15,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/10672\/revisions"}],"predecessor-version":[{"id":33376,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/posts\/10672\/revisions\/33376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media\/10674"}],"wp:attachment":[{"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/media?parent=10672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/categories?post=10672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/messweb-masters.de\/en\/wp-json\/wp\/v2\/tags?post=10672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}